{"id":2640,"date":"2020-12-18T13:09:07","date_gmt":"2020-12-18T12:09:07","guid":{"rendered":"https:\/\/www.pue.es\/blog\/lpi-otorga-a-pue-el-reconocimiento-maximo-como-partner-de-formacion-approved-training-partner-platinum\/"},"modified":"2024-02-08T14:00:36","modified_gmt":"2024-02-08T13:00:36","slug":"pue-approved-training-partner-platinum-lpi","status":"publish","type":"post","link":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/","title":{"rendered":"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n, Approved Training Partner Platinum"},"content":{"rendered":"<p><b>PUE ha sido reconocido como <a href=\"https:\/\/www.lpi.org\/articles\/pue-new-platinum-approved-training-partner-spain\" target=\"_blank\" rel=\"noopener noreferrer\">Approved Training Partner Platinum<\/a>, el nivel m\u00e1ximo dentro de esta figura, por Linux Professional Institute (LPI)<\/b><span style=\"font-weight: 400;\">. Como muestra del compromiso mutuo en el despliegue del programa de formaci\u00f3n y certificaci\u00f3n LPI en Espa\u00f1a, y tras una trayectoria de <\/span><b>m\u00e1s de 15 a\u00f1os<\/b><span style=\"font-weight: 400;\"> promoviendo y acercando la formaci\u00f3n y certificaci\u00f3n LPI a empresas y profesionales, PUE recibe este reconocimiento siendo el partner que m\u00e1s alumnos ha formado y certificado en LPI en nuestro pa\u00eds.<\/span><\/p>\n<div id=\"attachment_8204\" style=\"width: 643px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8204\" class=\"wp-image-8204 \" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2020-12-18-300x143.jpg\" alt=\"\" width=\"633\" height=\"302\" \/><p id=\"caption-attachment-8204\" class=\"wp-caption-text\">Javier Dom\u00ednguez, CEO de PUE, con Jon \u2018Maddog\u2019 Hall, presidente del consejo de Linux Professional Institute.<\/p><\/div>\n<p>&nbsp;<\/p>\n<h4><b>Formaci\u00f3n oficial con certificaci\u00f3n incluida en Linux<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Desde 2006, PUE impulsa para LPI su iniciativa acad\u00e9mica en Espa\u00f1a, que tiene como objetivo <\/span><b>acercar las certificaciones LPIC a empresas y profesionales<\/b><span style=\"font-weight: 400;\">, presentes y futuros, interesados en acreditar sus competencias en Linux.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adicionalmente a la figura de ATP Platinum, PUE tambi\u00e9n ha sido acreditado como <\/span><b>Channel Partner de LPI, reconociendo la labor de PUE Academy<\/b><span style=\"font-weight: 400;\"> en la difusi\u00f3n, reclutamiento y apoyo a los centros de LPI AAP, ATP y Linux Essentials a lo largo de la geograf\u00eda espa\u00f1ola. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desde 2009, PUE Academy ha formado a m\u00e1s de 1.500 instructores en los distintos cursos de LPIC, que han acercado la formaci\u00f3n en Linux de la mano de LPI a m\u00e1s de 15.000 estudiantes en estos a\u00f1os.\u00a0\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b>\u00bfQu\u00e9 es LPI?<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Linux Professional Institute (LPI) es una organizaci\u00f3n internacional sin \u00e1nimo de lucro que nace en 1999 con la misi\u00f3n de <\/span><b>promover y certificar capacidades esenciales en Linux<\/b><span style=\"font-weight: 400;\">, <\/span><b>C\u00f3digo Abierto y Software Libre<\/b><span style=\"font-weight: 400;\"> dise\u00f1ando ex\u00e1menes reconocidos e independientes de cualquier distribuci\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las certificaciones de LPI son altamente reconocidas y valoradas por la industria, habi\u00e9ndose convertido en un est\u00e1ndar que acredita el conocimiento en el \u00e1mbito Linux, al ser ex\u00e1menes de certificaci\u00f3n completamente independientes del proveedor y neutrales en cuanto a la distribuci\u00f3n.<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Certifications for open source systems thanks to Linux Professional Institute (LPI) | PUE\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/m6_xaalp_CI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p><span style=\"font-weight: 400;\">Como afirma<strong> Jon \u2018Maddog\u2019 Hall, presidente del consejo de Linux Professional Institute,<\/strong> la misi\u00f3n de LPI es ayudar a los miembros de la comunidad de Linux y de c\u00f3digo abierto a aumentar sus oportunidades profesionales, poniendo a su disposici\u00f3n recursos profesionales y certificaciones de habilidades.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apoyado por una red global de afiliados, LPI promueve el uso del c\u00f3digo abierto, mientras ayuda a garantizar que los profesionales de TI tienen las habilidades necesarias para ser competitivos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con <\/span><b>m\u00e1s de 500.000 certificaciones realizadas en 181 pa\u00edses y disponibles en 9 lenguas<\/b><span style=\"font-weight: 400;\">, LPI es referente mundial en la certificaci\u00f3n de profesionales Linux.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8210\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/diapo2-300x119.png\" alt=\"\" width=\"620\" height=\"246\" \/><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Desde PUE estamos muy agradecidos a todo el equipo de <strong>Linux Professional Institute (LPI)<\/strong> por reconocer nuestra experiencia y confiarnos el despliegue e implementaci\u00f3n de los cursos y las certificaciones oficiales del LPI en Espa\u00f1a.<\/span><\/p>\n<h4><\/h4>\n<p>&nbsp;<\/p>\n<h4><b>Links de inter\u00e9s:<\/b><\/h4>\n<p><a href=\"https:\/\/www.pue.es\/cursos\/lpi\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Formaci\u00f3n oficial con certificaci\u00f3n incluida en Linux<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.lpi.org\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Linux Professional Institute (LPI)<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contacto:<\/strong><\/p>\n<p><a href=\"mailto:training@pue.es\">training@pue.es<\/a> para formaci\u00f3n oficial en LPI.<\/p>\n<p><a href=\"mailto:exams@pue.es\">exams@pue.es<\/a> para certificaci\u00f3n oficial en LPI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por el Linux Professional Institute (LPI). Como muestra del compromiso mutuo en el despliegue del programa de formaci\u00f3n y certificaci\u00f3n LPI en Espa\u00f1a, y tras una trayectoria de m\u00e1s de 15 a\u00f1os promoviendo y acercando la formaci\u00f3n y certificaci\u00f3n LPI a empresas y profesionales, PUE recibe este reconocimiento siendo el partner que m\u00e1s alumnos ha formado y certificado en LPI en nuestro pa\u00eds.<\/p>\n","protected":false},"author":1,"featured_media":2641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,18],"tags":[],"class_list":["post-2640","post","type-post","status-publish","format-standard","has-post-thumbnail","category-corporate","category-formacion-certificacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n<\/title>\n<meta name=\"description\" content=\"PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por Linux Professional Institute.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por el Linux Professional Institute.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/\" \/>\n<meta property=\"og:site_name\" content=\"PUE Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-18T12:09:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-08T13:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2020\/12\/LPI-reconoce-a-PUE-como-Approved-Training-Partner-Linux.png\" \/>\n\t<meta property=\"og:image:width\" content=\"362\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin-blogpue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n\" \/>\n<meta name=\"twitter:description\" content=\"PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por el Linux Professional Institute.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2020\/12\/LPI-reconoce-a-PUE-como-Approved-Training-Partner-Linux.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-blogpue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/\"},\"author\":{\"name\":\"admin-blogpue\",\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/#\\\/schema\\\/person\\\/c1100c902cc7a9230c60a397b03adaed\"},\"headline\":\"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n, Approved Training Partner Platinum\",\"datePublished\":\"2020-12-18T12:09:07+00:00\",\"dateModified\":\"2024-02-08T13:00:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/\"},\"wordCount\":541,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/LPI-postblog.png\",\"articleSection\":[\"Corporate\",\"Formaci\u00f3n y certificaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/\",\"url\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/\",\"name\":\"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/LPI-postblog.png\",\"datePublished\":\"2020-12-18T12:09:07+00:00\",\"dateModified\":\"2024-02-08T13:00:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/#\\\/schema\\\/person\\\/c1100c902cc7a9230c60a397b03adaed\"},\"description\":\"PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por Linux Professional Institute.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/LPI-postblog.png\",\"contentUrl\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/LPI-postblog.png\",\"width\":362,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/pue-approved-training-partner-platinum-lpi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n y certificaci\u00f3n\",\"item\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/category\\\/formacion-certificacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n, Approved Training Partner Platinum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/\",\"name\":\"PUE Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/#\\\/schema\\\/person\\\/c1100c902cc7a9230c60a397b03adaed\",\"name\":\"admin-blogpue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"caption\":\"admin-blogpue\"},\"sameAs\":[\"http:\\\/\\\/www.eu4.pue.es\\\/blog\"],\"url\":\"https:\\\/\\\/www.pue.es\\\/blog\\\/author\\\/admin-blogpue\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n","description":"PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por Linux Professional Institute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/","og_locale":"es_ES","og_type":"article","og_title":"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n","og_description":"PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por el Linux Professional Institute.","og_url":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/","og_site_name":"PUE Blog","article_published_time":"2020-12-18T12:09:07+00:00","article_modified_time":"2024-02-08T13:00:36+00:00","og_image":[{"width":362,"height":286,"url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2020\/12\/LPI-reconoce-a-PUE-como-Approved-Training-Partner-Linux.png","type":"image\/png"}],"author":"admin-blogpue","twitter_card":"summary_large_image","twitter_title":"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n","twitter_description":"PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por el Linux Professional Institute.","twitter_image":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2020\/12\/LPI-reconoce-a-PUE-como-Approved-Training-Partner-Linux.png","twitter_misc":{"Escrito por":"admin-blogpue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/#article","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/"},"author":{"name":"admin-blogpue","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"headline":"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n, Approved Training Partner Platinum","datePublished":"2020-12-18T12:09:07+00:00","dateModified":"2024-02-08T13:00:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/"},"wordCount":541,"commentCount":0,"image":{"@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/LPI-postblog.png","articleSection":["Corporate","Formaci\u00f3n y certificaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/","url":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/","name":"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/#primaryimage"},"image":{"@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/LPI-postblog.png","datePublished":"2020-12-18T12:09:07+00:00","dateModified":"2024-02-08T13:00:36+00:00","author":{"@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"description":"PUE ha sido reconocido como Approved Training Partner Platinum, el nivel m\u00e1ximo dentro de esta figura, por Linux Professional Institute.","breadcrumb":{"@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/#primaryimage","url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/LPI-postblog.png","contentUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/LPI-postblog.png","width":362,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.pue.es\/blog\/pue-approved-training-partner-platinum-lpi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.pue.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n y certificaci\u00f3n","item":"https:\/\/www.pue.es\/blog\/category\/formacion-certificacion\/"},{"@type":"ListItem","position":3,"name":"LPI otorga a PUE el reconocimiento m\u00e1ximo como partner de formaci\u00f3n, Approved Training Partner Platinum"}]},{"@type":"WebSite","@id":"https:\/\/www.pue.es\/blog\/#website","url":"https:\/\/www.pue.es\/blog\/","name":"PUE Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pue.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed","name":"admin-blogpue","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","caption":"admin-blogpue"},"sameAs":["http:\/\/www.eu4.pue.es\/blog"],"url":"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/2640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/comments?post=2640"}],"version-history":[{"count":0,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/2640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media\/2641"}],"wp:attachment":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media?parent=2640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/categories?post=2640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/tags?post=2640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}