{"id":2401,"date":"2019-05-15T12:10:30","date_gmt":"2019-05-15T10:10:30","guid":{"rendered":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/"},"modified":"2024-02-22T16:07:03","modified_gmt":"2024-02-22T15:07:03","slug":"sneak-peek-de-la-6a-edicion-del-pue-academy-day","status":"publish","type":"post","link":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/","title":{"rendered":"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day!"},"content":{"rendered":"<p><a href=\"https:\/\/www.pue.es\/blog\/sneak-peek-pue-academy-day-6th-edition\/\"><img loading=\"lazy\" decoding=\"async\" class=\"language alignright wp-image-852\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/1456852799_Flag_of_United_Kingdom.png\" alt=\"1456852799_Flag_of_United_Kingdom\" width=\"32\" height=\"32\"><\/a><\/p>\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-01.jpg\" alt=\"Sneak Peek PUE Academy Day 1\" class=\"wp-image-6557\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-02.jpg\" alt=\"Sneak Peek PUE Academy Day 2\" class=\"wp-image-6558\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-03.jpg\" alt=\"Sneak Peek PUE Academy Day 3\" class=\"wp-image-6559\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/twitter.com\/search?q=%23PUEAcademyDay19&amp;src=typd\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-04.jpg\" alt=\"Sneak Peek PUE Academy Day 4\" class=\"wp-image-6560\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/twitter.com\/ticPUE\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-05.jpg\" alt=\"Sneak Peek PUE Academy Day 5\" class=\"wp-image-6561\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-06.jpg\" alt=\"Sneak Peek PUE Academy Day 6\" class=\"wp-image-6562\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.pue.es\/certificacion\/puemobile\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-07.jpg\" alt=\"Sneak Peek PUE Academy Day 7\" class=\"wp-image-6563\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.youtube.com\/watch?v=6HTV260YuxM\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-08.jpg\" alt=\"Sneak Peek PUE Academy Day 8\" class=\"wp-image-6564\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/banner-09.jpg\" alt=\"Sneak Peek PUE Academy Day 9\" class=\"wp-image-6565\"\/><\/figure>\n\n\n\n\n<h3><span style=\"color: #00ccff;\">Links de inter\u00e9s:<\/span><\/h3>\n<p>En breve habilitaremos el <a href=\"https:\/\/www.pue.es\/academy-day\/2019\">acceso a las presentaciones<\/a> que se proyectaron en la web del evento<\/p>\n<p style=\"text-align: left;\">\u00a0<a href=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/362x286-pue-academy-day.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"hidden alignnone wp-image-3411 size-full\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/362x286-pue-academy-day.jpg\" alt=\"pue_academy_day_2019\" width=\"364\" height=\"288\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del <strong>PUE Academy Day<\/strong>. \u00a1Consulta el Sneak Peek con los mejores momentos! <strong>#PUEAcademyDay19<\/strong><\/p>\n","protected":false},"author":1,"featured_media":2402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[230],"class_list":{"0":"post-2401","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-all-news","8":"tag-pue-academy-day-2019"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day! | PUE Blog<\/title>\n<meta name=\"description\" content=\"El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del PUE Academy Day.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day! | PUE Blog\" \/>\n<meta property=\"og:description\" content=\"El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del PUE Academy Day.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/\" \/>\n<meta property=\"og:site_name\" content=\"PUE Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-15T10:10:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-22T15:07:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"362\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-blogpue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day! | PUE Blog\" \/>\n<meta name=\"twitter:description\" content=\"El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del PUE Academy Day.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-blogpue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/\"},\"author\":{\"name\":\"admin-blogpue\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"headline\":\"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day!\",\"datePublished\":\"2019-05-15T10:10:30+00:00\",\"dateModified\":\"2024-02-22T15:07:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/\"},\"wordCount\":30,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg\",\"keywords\":[\"PUE Academy Day 2019\"],\"articleSection\":[\"All news\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/\",\"url\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/\",\"name\":\"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day! | PUE Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg\",\"datePublished\":\"2019-05-15T10:10:30+00:00\",\"dateModified\":\"2024-02-22T15:07:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"description\":\"El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del PUE Academy Day.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#primaryimage\",\"url\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg\",\"contentUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg\",\"width\":362,\"height\":286,\"caption\":\"sneak-peek-pue-academy-day\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.pue.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All news\",\"item\":\"https:\/\/www.pue.es\/blog\/en\/category\/all-news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pue.es\/blog\/#website\",\"url\":\"https:\/\/www.pue.es\/blog\/\",\"name\":\"PUE Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pue.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\",\"name\":\"admin-blogpue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"caption\":\"admin-blogpue\"},\"sameAs\":[\"http:\/\/www.eu4.pue.es\/blog\"],\"url\":\"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day! | PUE Blog","description":"El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del PUE Academy Day.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day! | PUE Blog","og_description":"El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del PUE Academy Day.","og_url":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/","og_site_name":"PUE Blog","article_published_time":"2019-05-15T10:10:30+00:00","article_modified_time":"2024-02-22T15:07:03+00:00","og_image":[{"width":362,"height":286,"url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg","type":"image\/jpeg"}],"author":"admin-blogpue","twitter_card":"summary_large_image","twitter_title":"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day! | PUE Blog","twitter_description":"El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del PUE Academy Day.","twitter_image":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg","twitter_misc":{"Escrito por":"admin-blogpue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#article","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/"},"author":{"name":"admin-blogpue","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"headline":"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day!","datePublished":"2019-05-15T10:10:30+00:00","dateModified":"2024-02-22T15:07:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/"},"wordCount":30,"commentCount":0,"image":{"@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg","keywords":["PUE Academy Day 2019"],"articleSection":["All news"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/","url":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/","name":"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day! | PUE Blog","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#primaryimage"},"image":{"@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg","datePublished":"2019-05-15T10:10:30+00:00","dateModified":"2024-02-22T15:07:03+00:00","author":{"@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"description":"El pasado 8 de mayo en Madrid y con el objetivo de facilitar la docencia en tecnolog\u00eda, se celebr\u00f3 la 6\u00aa edici\u00f3n del PUE Academy Day.","breadcrumb":{"@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#primaryimage","url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg","contentUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/362x286-pue-academy-day.jpg","width":362,"height":286,"caption":"sneak-peek-pue-academy-day"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pue.es\/blog\/sneak-peek-de-la-6a-edicion-del-pue-academy-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.pue.es\/blog\/"},{"@type":"ListItem","position":2,"name":"All news","item":"https:\/\/www.pue.es\/blog\/en\/category\/all-news\/"},{"@type":"ListItem","position":3,"name":"\u00a1Sneak Peek de la 6\u00aa Edici\u00f3n del PUE Academy Day!"}]},{"@type":"WebSite","@id":"https:\/\/www.pue.es\/blog\/#website","url":"https:\/\/www.pue.es\/blog\/","name":"PUE Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pue.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed","name":"admin-blogpue","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","caption":"admin-blogpue"},"sameAs":["http:\/\/www.eu4.pue.es\/blog"],"url":"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/2401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/comments?post=2401"}],"version-history":[{"count":0,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/2401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media\/2402"}],"wp:attachment":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media?parent=2401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/categories?post=2401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/tags?post=2401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}