{"id":2323,"date":"2019-02-20T16:13:07","date_gmt":"2019-02-20T15:13:07","guid":{"rendered":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/"},"modified":"2024-02-22T18:15:52","modified_gmt":"2024-02-22T17:15:52","slug":"formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue","status":"publish","type":"post","link":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/","title":{"rendered":"Formaci\u00f3n sobre new features de Big Data Cloudera 6.x en el primer TechDay de PUE"},"content":{"rendered":"\n<p>Comprometidos en ofrecer beneficios y el mejor servicio posible a los clientes, PUE crea, bajo su figura de <strong>Gold Partner de Cloudera<\/strong>, los TechDays: jornadas de formaci\u00f3n t\u00e9cnica avanzada para promover el uso de la tecnolog\u00eda a trav\u00e9s de la&nbsp; implementaci\u00f3n de proyectos Big Data as\u00ed&nbsp; como la administraci\u00f3n de plataformas de Cloudera.  <\/p>\n\n\n\n<!--more-->\n\n\n\n<p><strong>Con&nbsp;la&nbsp;colaboraci\u00f3n&nbsp;<\/strong>de <a href=\"http:\/\/cloudera.com\/\">Cloudera<\/a>, l\u00edder en la distribuci\u00f3n de Hadoop , el pasado 12 de febrero se llev\u00f3 a cabo el <strong>primer TechDay en <a href=\"http:\/\/pue.es\/\">PUE<\/a> Madrid<\/strong>.  El  objetivo del TechDay es mantener a nuestros clientes actualizados y que aprovechen al m\u00e1ximo las tecnolog\u00edas aplicadas a las diferentes \u00e1reas de negocio<strong>&nbsp;.<\/strong><\/p>\n\n\n\n<p><strong>Roberto L\u00f3pez, Business Director de PUE<\/strong>, dio la bienvenida a los participantes destacando la responsabilidad y compromiso de PUE por compartir conocimiento para, as\u00ed, contribuir a la implementaci\u00f3n de estrategias Data Driven eficientes: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201c<strong>Somos una empresa de servicios profesionales especialistas en Big Data.<\/strong>  Tenemos claro el potencial de \u00e9sta tecnolog\u00eda, pero, sobre todo, sabemos que nuestra labor es <strong>proporcionar el mayor beneficio a nuestros clientes por medio del conocimiento tecnol\u00f3gico que poseemos<\/strong>.&nbsp; Queremos asegurar el \u00e9xito de todos los proyectos de Big Data con un servicio de calidad.\u201d<\/p><cite>Roberto L\u00f3pez. Business Director PUE<\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Update en Big Data: Cloudera 6.x<\/h2>\n\n\n\n<p>Durante esta primera edici\u00f3n, <strong>Arnaud Delanoue,  Big Data Architect en PUE<\/strong>, explic\u00f3 las nuevas caracter\u00edsticas de <strong>Cloudera Enterprise 6.x<\/strong>, que cuenta con importantes avances en <strong>productividad, machine learning y analytics <\/strong>que&nbsp;optimizan los recursos inform\u00e1ticos para maximizar el rendimiento.  Se hizo especial hincapi\u00e9 en tres novedades muy interesantes: <strong>HDFS Erasure Coding, Spark Structured Streaming y Solr 7<\/strong>. <\/p>\n\n\n\n<ul class=\"wp-block-gallery aligncenter columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/TechDay_PUE_13-1024x563.jpg\" alt=\"Update Big Data\" data-id=\"5794\" data-link=\"https:\/\/www.pue.es\/blog\/techday-para-proporcionar-a-las-empresas-updates-tecnologicos\/techday_pue_13\/\" class=\"wp-image-5794\"\/><figcaption>Update Solr 7 por Arnaud Delanoue<\/figcaption><\/figure><\/li><\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abEntendemos que <strong>implementar adecuadamente la tecnolog\u00eda de acuerdo al caso de uso<\/strong>, <strong>es<\/strong> <strong>uno de los mayores retos que las empresas enfrentan en el momento de  incorporar un proyecto de Big Data en su estrategia<\/strong>.  Lo que pretende el TechDay es brindar conocimientos a nuestros clientes para que tengan herramientas con las cuales afrontar esos retos y una mejor visi\u00f3n del alcance de las diferentes tecnolog\u00edas.\u00bb <\/p><cite>Sergio Rodr\u00edguez de Guzm\u00e1n. CTO PUE <\/cite><\/blockquote>\n\n\n\n<ul class=\"wp-block-gallery aligncenter columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/TechDay_PUE_4.jpg\" alt=\"Update Big Data\" data-id=\"5795\" data-link=\"https:\/\/www.pue.es\/blog\/techday-para-proporcionar-a-las-empresas-updates-tecnologicos\/techday_pue_4\/\" class=\"wp-image-5795\"\/><\/figure><\/li><\/ul>\n\n\n\n<p>Satisfechos con la primera edici\u00f3n del TechDay, PUE tiene programadas diferentes ediciones a lo largo del a\u00f1o para otras tecnolog\u00edas del entorno Big Data, como StreamSets o Kudu.<\/p>\n\n\n\n<p>T\u00e9cnicos procedentes de importantes empresas espa\u00f1olas participaron de forma activa en la jornada. El grupo descubri\u00f3 a fondo todos los beneficios, funciones y capacidades que Cloudera Enterprise 6.x puede aportar al negocio.  Adem\u00e1s, los participantes tuvieron la oportunidad  de compartir experiencias y conocimientos con colegas del sector, enriqueciendo la experiencia de todos.  <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sobre PUE<\/strong><\/h4>\n\n\n\n<p><strong>Como l\u00edder de Big&nbsp;Data, Cloud, Microservicios, NoSQL y DevOps en Espa\u00f1a<\/strong>,&nbsp;el&nbsp;objetivo&nbsp;de&nbsp;PUE&nbsp;es, siempre, ofrecer a sus clientes las mejores soluciones con las \u00faltimas tecnolog\u00edas: soluciones innovadoras propuestas por un <strong>equipo t\u00e9cnico certificado, expertos en Administraci\u00f3n, Analista de Datos, Cient\u00edfico de Datos y Desarrollo<\/strong>.<\/p>\n\n\n<p>Para m\u00e1s informaci\u00f3n sobre los servicios Big Data de PUE:<\/p>\n<p><a href=\"https:\/\/www.pue.es\/consultoria-tic\">Servicios y soluciones en Big Data con PUE<\/a><br \/><a href=\"https:\/\/www.pue.es\/cursos\/cloudera\">Formaci\u00f3n y certificaci\u00f3n oficial en Big Data con Cloudera<\/a><\/p>\n<h6><span style=\"color: #00ccff;\">Contacta para saber m\u00e1s en:<\/span><\/h6>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/icon-email_consultoria_cta.jpg\" alt=\"mail\" width=\"30\" height=\"30\" \/> <a href=\"mailto:consulting@pue.es\">consulting@pue.es<\/a> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/icon-form.jpg\" alt=\"icon-form\" width=\"50\" height=\"50\" \/><a href=\"https:\/\/www.pue.es\/consultoria-tic\/contacto\">Solicitud de informaci\u00f3n para la implantaci\u00f3n de proyectos en Big Data<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/icon-email_consultoria_cta.jpg\" alt=\"mail\" width=\"30\" height=\"30\" \/> <a href=\"mailto:training@pue.es\">training@pue.es<\/a> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/icon-form.jpg\" alt=\"icon-form\" width=\"50\" height=\"50\" \/><a href=\"https:\/\/www.pue.es\/cursos\/contacto\">Solicitud de informaci\u00f3n para formaci\u00f3n y certifcaci\u00f3n en Cloudera<\/a><\/p>\n<p style=\"text-align: left;\">\u00a0<a href=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/Que-es-Big-Data-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"hidden alignnone wp-image-3411 size-full\" src=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/TechDay-Update-BigData.jpg\" width=\"364\" height=\"288\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Comprometidos en ofrecer beneficios y el mejor servicio posible a los clientes, PUE crea, bajo su figura de Gold Partner de Cloudera, los TechDays: jornadas de formaci\u00f3n t\u00e9cnica avanzada para promover el uso de la tecnolog\u00eda a trav\u00e9s de la&nbsp; implementaci\u00f3n de proyectos Big Data as\u00ed&nbsp; como la administraci\u00f3n de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148],"tags":[77,175,183,80,185,186],"class_list":{"0":"post-2323","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-servicios-data-cloud","8":"tag-cloudera","9":"tag-cloudera-gold-partner","10":"tag-hdfs","11":"tag-servicios","12":"tag-solr7","13":"tag-spark-streaming"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TechDay, formaci\u00f3n y update Big Data Cloudera para empresas<\/title>\n<meta name=\"description\" content=\"Los TechDays son jornadas de update en Big Data Cloudera para promover el uso de las \u00faltimas tecnolog\u00edas y asegurar el \u00e9xito de los proyectos de Big Data.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TechDay, formaci\u00f3n y update Big Data Cloudera para empresas\" \/>\n<meta property=\"og:description\" content=\"Los TechDays son jornadas de update en Big Data Cloudera para promover el uso de las \u00faltimas tecnolog\u00edas y asegurar el \u00e9xito de los proyectos de Big Data.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/\" \/>\n<meta property=\"og:site_name\" content=\"PUE Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-20T15:13:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-22T17:15:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"362\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-blogpue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"TechDay, formaci\u00f3n y update Big Data Cloudera para empresas\" \/>\n<meta name=\"twitter:description\" content=\"Los TechDays son jornadas de update en Big Data Cloudera para promover el uso de las \u00faltimas tecnolog\u00edas y asegurar el \u00e9xito de los proyectos de Big Data.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-blogpue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/\"},\"author\":{\"name\":\"admin-blogpue\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"headline\":\"Formaci\u00f3n sobre new features de Big Data Cloudera 6.x en el primer TechDay de PUE\",\"datePublished\":\"2019-02-20T15:13:07+00:00\",\"dateModified\":\"2024-02-22T17:15:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/\"},\"wordCount\":598,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg\",\"keywords\":[\"cloudera\",\"Cloudera Gold Partner\",\"HDFS\",\"servicios\",\"Solr7\",\"Spark Streaming\"],\"articleSection\":[\"Servicios Data &amp; Cloud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/\",\"url\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/\",\"name\":\"TechDay, formaci\u00f3n y update Big Data Cloudera para empresas\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg\",\"datePublished\":\"2019-02-20T15:13:07+00:00\",\"dateModified\":\"2024-02-22T17:15:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"description\":\"Los TechDays son jornadas de update en Big Data Cloudera para promover el uso de las \u00faltimas tecnolog\u00edas y asegurar el \u00e9xito de los proyectos de Big Data.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#primaryimage\",\"url\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg\",\"contentUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg\",\"width\":362,\"height\":286,\"caption\":\"TechDay-Update-BigData\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.pue.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios Data &amp; Cloud\",\"item\":\"https:\/\/www.pue.es\/blog\/category\/servicios-data-cloud\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Formaci\u00f3n sobre new features de Big Data Cloudera 6.x en el primer TechDay de PUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pue.es\/blog\/#website\",\"url\":\"https:\/\/www.pue.es\/blog\/\",\"name\":\"PUE Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pue.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\",\"name\":\"admin-blogpue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"caption\":\"admin-blogpue\"},\"sameAs\":[\"http:\/\/www.eu4.pue.es\/blog\"],\"url\":\"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TechDay, formaci\u00f3n y update Big Data Cloudera para empresas","description":"Los TechDays son jornadas de update en Big Data Cloudera para promover el uso de las \u00faltimas tecnolog\u00edas y asegurar el \u00e9xito de los proyectos de Big Data.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/","og_locale":"es_ES","og_type":"article","og_title":"TechDay, formaci\u00f3n y update Big Data Cloudera para empresas","og_description":"Los TechDays son jornadas de update en Big Data Cloudera para promover el uso de las \u00faltimas tecnolog\u00edas y asegurar el \u00e9xito de los proyectos de Big Data.","og_url":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/","og_site_name":"PUE Blog","article_published_time":"2019-02-20T15:13:07+00:00","article_modified_time":"2024-02-22T17:15:52+00:00","og_image":[{"width":362,"height":286,"url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg","type":"image\/jpeg"}],"author":"admin-blogpue","twitter_card":"summary_large_image","twitter_title":"TechDay, formaci\u00f3n y update Big Data Cloudera para empresas","twitter_description":"Los TechDays son jornadas de update en Big Data Cloudera para promover el uso de las \u00faltimas tecnolog\u00edas y asegurar el \u00e9xito de los proyectos de Big Data.","twitter_image":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg","twitter_misc":{"Escrito por":"admin-blogpue","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#article","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/"},"author":{"name":"admin-blogpue","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"headline":"Formaci\u00f3n sobre new features de Big Data Cloudera 6.x en el primer TechDay de PUE","datePublished":"2019-02-20T15:13:07+00:00","dateModified":"2024-02-22T17:15:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/"},"wordCount":598,"commentCount":0,"image":{"@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg","keywords":["cloudera","Cloudera Gold Partner","HDFS","servicios","Solr7","Spark Streaming"],"articleSection":["Servicios Data &amp; Cloud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/","url":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/","name":"TechDay, formaci\u00f3n y update Big Data Cloudera para empresas","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#primaryimage"},"image":{"@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg","datePublished":"2019-02-20T15:13:07+00:00","dateModified":"2024-02-22T17:15:52+00:00","author":{"@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"description":"Los TechDays son jornadas de update en Big Data Cloudera para promover el uso de las \u00faltimas tecnolog\u00edas y asegurar el \u00e9xito de los proyectos de Big Data.","breadcrumb":{"@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#primaryimage","url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg","contentUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/TechDay-Update-BigData.jpg","width":362,"height":286,"caption":"TechDay-Update-BigData"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pue.es\/blog\/formacion-sobre-new-features-de-big-data-cloudera-6-x-en-el-primer-techday-de-pue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.pue.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Servicios Data &amp; Cloud","item":"https:\/\/www.pue.es\/blog\/category\/servicios-data-cloud\/"},{"@type":"ListItem","position":3,"name":"Formaci\u00f3n sobre new features de Big Data Cloudera 6.x en el primer TechDay de PUE"}]},{"@type":"WebSite","@id":"https:\/\/www.pue.es\/blog\/#website","url":"https:\/\/www.pue.es\/blog\/","name":"PUE Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pue.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed","name":"admin-blogpue","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","caption":"admin-blogpue"},"sameAs":["http:\/\/www.eu4.pue.es\/blog"],"url":"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/2323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/comments?post=2323"}],"version-history":[{"count":0,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/2323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media\/2324"}],"wp:attachment":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media?parent=2323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/categories?post=2323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/tags?post=2323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}