{"id":1722,"date":"2013-10-21T09:26:37","date_gmt":"2013-10-21T07:26:37","guid":{"rendered":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/"},"modified":"2024-02-28T21:53:36","modified_gmt":"2024-02-28T20:53:36","slug":"presentacion-de-la-certificacion-oficial-de-idiomas-bulats","status":"publish","type":"post","link":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/","title":{"rendered":"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats"},"content":{"rendered":"<p style=\"text-align: justify;\">El pasado 2 de octubre <strong>PUE celebr\u00f3 una charla-desayuno<\/strong> para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol, <strong>ha incorporado a su \u00e1rea de certificaciones: el Test Bulats (Business Language Testing Service)<\/strong>. Una prueba flexible, fiable y asequible que, orientada exclusivamente al mundo empresarial, acredita el ingl\u00e9s a nivel profesional.<!--more--><\/p>\n<p style=\"text-align: justify;\">La celebraci\u00f3n del encuentro fue exitosa. Tuvo una gran acogida entre todos los asistentes, representados por profesionales y empresas del sector TIC, estudiantes, as\u00ed como organismos y entidades como Barcelona Activa y el Departament d\u2019 Ensenyament de la Generalitat de Catalunya.<\/p>\n<p style=\"text-align: justify;\">La jornada se abri\u00f3 con una <strong>presentaci\u00f3n de PUE a cargo de su Director Gerente, Orlando Dom\u00ednguez<\/strong>, quien destac\u00f3 la <i>capacidad de comunicarnos en ingl\u00e9s como carencia generalizada<\/i>:\u00a0<strong>\u201cEstamos en un mercado internacional, afirm\u00f3, pero nos faltan recursos y herramientas para poder desarrollarnos\u201d<\/strong>.<\/p>\n<div class=\"row\">\n<div class=\"col-xs-6\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-1.png\" alt=\"\" \/><\/div>\n<div class=\"col-xs-6\" style=\"text-align: center;\"><img decoding=\"async\" src=\"http:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png\" alt=\"\" \/><\/div>\n<\/div>\n<p style=\"font-size: 12px; text-align: center;\"><em>Presentaci\u00f3n de PUE a cargo de su Director Gerente Orlando Dom\u00ednguez<\/em><\/p>\n<p style=\"text-align: justify;\">Se cont\u00f3 con la <strong>presencia de Xavier Ballesteros, responsable de Cambridge English Language Assessment<\/strong>, quien tr\u00e1s la intervenci\u00f3n de Orlando Dom\u00ednguez profundiz\u00f3 sobre los detalles y beneficios de la certificaci\u00f3n. \u201c<strong>Bulats no mide funciones gramaticales, mide la capacidad de utilizar el idioma en situaciones reales de la actividad empresarial<\/strong>: reuniones, negociaci\u00f3n, atenci\u00f3n al cliente, elaboraci\u00f3n de informes, \u00f3rdenes de compra,\u2026\u201d, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s del prestigio y reconocimiento que la certificaci\u00f3n proporciona a empresas y profesionales, Ballesteros cit\u00f3 algunos escenarios donde el test Bulats se convierte en una herramienta de gran utilidad: Auditor\u00edas ling\u00fc\u00edsticas en caso de adquisiciones; movilidad del personal a centros de trabajo en el extranjero; selecci\u00f3n del personal por los departamentos de RRHH y empresas de selecci\u00f3n,\u2026<\/p>\n<div class=\"row\">\n<div class=\"col-xs-6\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-3.png\" alt=\"\" \/><\/div>\n<div class=\"col-xs-6\" style=\"text-align: center;\"><img decoding=\"async\" src=\"http:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-4.png\" alt=\"\" \/><\/div>\n<\/div>\n<p style=\"text-align: center;\"><em>Xavier Ballesteros, responsable de Cambridge English Language Assessment<\/em><\/p>\n<p style=\"text-align: justify;\">Para finalizar, la intervenci\u00f3n de Valent\u00edn Rozenski, Responsable del \u00c1rea de Certificaciones Oficiales de PUE, mostr\u00f3 el proceso de inscripci\u00f3n y reservas del examen Bulats en PUE. Seguida de la exposici\u00f3n de Luis C\u00e9spedes, Director Educaci\u00f3n PUE, sobre los detalles del curso online de preparaci\u00f3n a la prueba. Una c\u00e1psula formativa que, adem\u00e1s de preparar para el test, proporciona recursos adicionales y ayuda a situar al candidato en lo que a su nivel y competencias ling\u00fc\u00edsticas se refiere.<\/p>\n<blockquote>\n<h6 style=\"text-align: justify;\">Con esta nueva iniciativa, PUE apuesta por <i>la acreditaci\u00f3n oficial del ingl\u00e9s necesario para la actividad laboral<\/i> como ventaja competitiva para las empresas y profesionales del sector TIC.<\/h6>\n<\/blockquote>\n<p style=\"text-align: justify;\">M\u00e1s informaci\u00f3n en: <span style=\"text-decoration: underline;\"><strong><span style=\"color: #00ccff;\"><a style=\"color: #00ccff; text-decoration: underline;\" href=\"https:\/\/www.pue.es\/certificacion\/examen-bulats\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.pue.es\/bulats<\/a><\/span><\/strong><\/span><br \/>\nCanal atenci\u00f3n empresas y profesionales: <span style=\"text-decoration: underline;\"><strong><span style=\"color: #00ccff; text-decoration: underline;\"><a style=\"color: #00ccff; text-decoration: underline;\" href=\"mailto:training@pue.es\" target=\"_blank\" rel=\"noopener noreferrer\">training@pue.es<\/a><\/span><\/strong><\/span><\/p>\n<div class=\"row\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol, ha incorporado a su \u00e1rea de certificaciones: el Test Bulats (Business Language Testing Service). Una prueba flexible, fiable y asequible que, orientada exclusivamente al mundo empresarial, acredita el ingl\u00e9s&#8230;<\/p>\n","protected":false},"author":1,"featured_media":130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[40,41,42],"class_list":{"0":"post-1722","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-formacion-certificacion","8":"tag-bulats","9":"tag-cambridge","10":"tag-english"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats | PUE Blog<\/title>\n<meta name=\"description\" content=\"El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats | PUE Blog\" \/>\n<meta property=\"og:description\" content=\"El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/\" \/>\n<meta property=\"og:site_name\" content=\"PUE Blog\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-21T07:26:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T20:53:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin-blogpue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats | PUE Blog\" \/>\n<meta name=\"twitter:description\" content=\"El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-blogpue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/\"},\"author\":{\"name\":\"admin-blogpue\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"headline\":\"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats\",\"datePublished\":\"2013-10-21T07:26:37+00:00\",\"dateModified\":\"2024-02-28T20:53:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/\"},\"wordCount\":441,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png\",\"keywords\":[\"bulats\",\"cambridge\",\"english\"],\"articleSection\":[\"Formaci\u00f3n y certificaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/\",\"url\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/\",\"name\":\"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats | PUE Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png\",\"datePublished\":\"2013-10-21T07:26:37+00:00\",\"dateModified\":\"2024-02-28T20:53:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"description\":\"El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#primaryimage\",\"url\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png\",\"contentUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png\",\"width\":320,\"height\":243,\"caption\":\"presentacion-de-la-certificacion-oficial-de-idiomas-bulats\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.pue.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n y certificaci\u00f3n\",\"item\":\"https:\/\/www.pue.es\/blog\/category\/formacion-certificacion\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pue.es\/blog\/#website\",\"url\":\"https:\/\/www.pue.es\/blog\/\",\"name\":\"PUE Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pue.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\",\"name\":\"admin-blogpue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"caption\":\"admin-blogpue\"},\"sameAs\":[\"http:\/\/www.eu4.pue.es\/blog\"],\"url\":\"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats | PUE Blog","description":"El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats | PUE Blog","og_description":"El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol","og_url":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/","og_site_name":"PUE Blog","article_published_time":"2013-10-21T07:26:37+00:00","article_modified_time":"2024-02-28T20:53:36+00:00","og_image":[{"width":320,"height":243,"url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png","type":"image\/png"}],"author":"admin-blogpue","twitter_card":"summary_large_image","twitter_title":"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats | PUE Blog","twitter_description":"El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol","twitter_image":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png","twitter_misc":{"Escrito por":"admin-blogpue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#article","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/"},"author":{"name":"admin-blogpue","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"headline":"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats","datePublished":"2013-10-21T07:26:37+00:00","dateModified":"2024-02-28T20:53:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/"},"wordCount":441,"commentCount":0,"image":{"@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png","keywords":["bulats","cambridge","english"],"articleSection":["Formaci\u00f3n y certificaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/","url":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/","name":"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats | PUE Blog","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#primaryimage"},"image":{"@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png","datePublished":"2013-10-21T07:26:37+00:00","dateModified":"2024-02-28T20:53:36+00:00","author":{"@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"description":"El pasado 2 de octubre PUE celebr\u00f3 una charla-desayuno para presentar la certificaci\u00f3n oficial que, gracias al acuerdo con Cambridge Essol","breadcrumb":{"@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#primaryimage","url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png","contentUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news7-2.png","width":320,"height":243,"caption":"presentacion-de-la-certificacion-oficial-de-idiomas-bulats"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pue.es\/blog\/presentacion-de-la-certificacion-oficial-de-idiomas-bulats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.pue.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n y certificaci\u00f3n","item":"https:\/\/www.pue.es\/blog\/category\/formacion-certificacion\/"},{"@type":"ListItem","position":3,"name":"Presentaci\u00f3n de la certificaci\u00f3n oficial de idiomas Bulats"}]},{"@type":"WebSite","@id":"https:\/\/www.pue.es\/blog\/#website","url":"https:\/\/www.pue.es\/blog\/","name":"PUE Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pue.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed","name":"admin-blogpue","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","caption":"admin-blogpue"},"sameAs":["http:\/\/www.eu4.pue.es\/blog"],"url":"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/1722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/comments?post=1722"}],"version-history":[{"count":0,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/1722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media\/130"}],"wp:attachment":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media?parent=1722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/categories?post=1722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/tags?post=1722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}