{"id":1721,"date":"2013-09-30T09:18:08","date_gmt":"2013-09-30T07:18:08","guid":{"rendered":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/"},"modified":"2024-02-28T21:55:05","modified_gmt":"2024-02-28T20:55:05","slug":"desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion","status":"publish","type":"post","link":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/","title":{"rendered":"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las <strong>jornadas t\u00e9cnicas<\/strong> que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las <strong>competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas<\/strong> en la actualidad.<\/p>\n<p style=\"text-align: justify;\">Los asistentes, en su mayor\u00eda desarrolladores Java en activo <!--more-->as\u00ed como profesionales que deseaban introducirse en la tecnolog\u00eda, se llevaron una visi\u00f3n \u00fatil de la plataforma: casos de \u00e9xito, herramientas m\u00e1s utilizadas, problem\u00e1tica a la que se enfrentan los equipos de trabajo, las \u00faltimas tendencias, exposici\u00f3n de los productos que forman parte del ecosistema,\u2026<\/p>\n<p style=\"text-align: justify;\">La jornada, orientada a transferir conocimientos de aplicaci\u00f3n pr\u00e1ctica, se desarroll\u00f3 en un ambiente ameno, din\u00e1mico y muy interactivo. Ponemos a disposici\u00f3n de los interesados una muestra del material de presentaci\u00f3n en el que se apoyaron nuestros instructores <strong><span style=\"text-decoration: underline;\"><span style=\"color: #00ccff;\"><a style=\"color: #00ccff; text-decoration: underline;\" href=\"http:\/\/prezi.com\/2jfvgn5m4vzj\/desarrollo-de-apps-en-la-plataforma-java\/\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a><\/span><\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">En PUE disponemos de una <strong>amplia oferta formativa en cursos de calendario de Java<\/strong>. Toda la informaci\u00f3n en: <span style=\"color: #00ccff;\"><strong><span style=\"text-decoration: underline;\"><a style=\"color: #00ccff; text-decoration: underline;\" href=\"https:\/\/www.pue.es\/cursos\" target=\"_blank\" rel=\"noopener noreferrer\">www.pue.es\/cursos<\/a><\/span><\/strong><\/span>.<\/p>\n<p>Canal de atenci\u00f3n alumno y empresa: <strong><span style=\"text-decoration: underline;\"><span style=\"color: #00ccff; text-decoration: underline;\"><a style=\"color: #00ccff; text-decoration: underline;\" href=\"mailto:training@pue.es\" target=\"_blank\" rel=\"noopener noreferrer\">training@pue.es<\/a><\/span><\/span><\/strong>.<\/p>\n<div style=\"width: 416px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"http:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png\" alt=\"\" width=\"406\" height=\"295\" \/><p class=\"wp-caption-text\">Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad. Los asistentes, en su mayor\u00eda desarrolladores Java en activo<\/p>\n","protected":false},"author":1,"featured_media":125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[35,36,37,38],"class_list":{"0":"post-1721","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-formacion-certificacion","8":"tag-cursos-java","9":"tag-desarrolladores-java","10":"tag-java","11":"tag-tecnologia"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n | PUE Blog<\/title>\n<meta name=\"description\" content=\"El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n | PUE Blog\" \/>\n<meta property=\"og:description\" content=\"El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/\" \/>\n<meta property=\"og:site_name\" content=\"PUE Blog\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-30T07:18:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T20:55:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"509\" \/>\n\t<meta property=\"og:image:height\" content=\"382\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin-blogpue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n | PUE Blog\" \/>\n<meta name=\"twitter:description\" content=\"El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-blogpue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/\"},\"author\":{\"name\":\"admin-blogpue\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"headline\":\"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n\",\"datePublished\":\"2013-09-30T07:18:08+00:00\",\"dateModified\":\"2024-02-28T20:55:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/\"},\"wordCount\":218,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png\",\"keywords\":[\"cursos java\",\"desarrolladores java\",\"java\",\"tecnolog\u00eda\"],\"articleSection\":[\"Formaci\u00f3n y certificaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/\",\"url\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/\",\"name\":\"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n | PUE Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png\",\"datePublished\":\"2013-09-30T07:18:08+00:00\",\"dateModified\":\"2024-02-28T20:55:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"description\":\"El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#primaryimage\",\"url\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png\",\"contentUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png\",\"width\":509,\"height\":382,\"caption\":\"desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.pue.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n y certificaci\u00f3n\",\"item\":\"https:\/\/www.pue.es\/blog\/category\/formacion-certificacion\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pue.es\/blog\/#website\",\"url\":\"https:\/\/www.pue.es\/blog\/\",\"name\":\"PUE Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pue.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\",\"name\":\"admin-blogpue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"caption\":\"admin-blogpue\"},\"sameAs\":[\"http:\/\/www.eu4.pue.es\/blog\"],\"url\":\"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n | PUE Blog","description":"El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/","og_locale":"es_ES","og_type":"article","og_title":"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n | PUE Blog","og_description":"El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad.","og_url":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/","og_site_name":"PUE Blog","article_published_time":"2013-09-30T07:18:08+00:00","article_modified_time":"2024-02-28T20:55:05+00:00","og_image":[{"width":509,"height":382,"url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png","type":"image\/png"}],"author":"admin-blogpue","twitter_card":"summary_large_image","twitter_title":"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n | PUE Blog","twitter_description":"El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad.","twitter_image":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png","twitter_misc":{"Escrito por":"admin-blogpue","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#article","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/"},"author":{"name":"admin-blogpue","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"headline":"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n","datePublished":"2013-09-30T07:18:08+00:00","dateModified":"2024-02-28T20:55:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/"},"wordCount":218,"commentCount":0,"image":{"@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png","keywords":["cursos java","desarrolladores java","java","tecnolog\u00eda"],"articleSection":["Formaci\u00f3n y certificaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/","url":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/","name":"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n | PUE Blog","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#primaryimage"},"image":{"@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png","datePublished":"2013-09-30T07:18:08+00:00","dateModified":"2024-02-28T20:55:05+00:00","author":{"@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"description":"El seminario se celebr\u00f3 el pasado 13 de septiembre como parte de las jornadas t\u00e9cnicas que PUE est\u00e1 ofreciendo a empresas, profesionales y estudiantes en respuesta a las competencias y habilidades tecnol\u00f3gicas que est\u00e1n siendo m\u00e1s demandadas en la actualidad.","breadcrumb":{"@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#primaryimage","url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png","contentUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/news6-1.png","width":509,"height":382,"caption":"desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pue.es\/blog\/desarrollo-de-aplicaciones-en-java-nueva-jornada-tecnica-de-pue-celebrada-con-gran-aceptacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.pue.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n y certificaci\u00f3n","item":"https:\/\/www.pue.es\/blog\/category\/formacion-certificacion\/"},{"@type":"ListItem","position":3,"name":"Desarrollo de aplicaciones en Java: Nueva jornada t\u00e9cnica de PUE celebrada con gran aceptaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.pue.es\/blog\/#website","url":"https:\/\/www.pue.es\/blog\/","name":"PUE Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pue.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed","name":"admin-blogpue","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","caption":"admin-blogpue"},"sameAs":["http:\/\/www.eu4.pue.es\/blog"],"url":"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/1721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":0,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media\/125"}],"wp:attachment":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}