{"id":1716,"date":"2015-07-21T08:05:55","date_gmt":"2015-07-21T06:05:55","guid":{"rendered":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/"},"modified":"2024-02-28T21:14:41","modified_gmt":"2024-02-28T20:14:41","slug":"pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn","status":"publish","type":"post","link":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/","title":{"rendered":"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn"},"content":{"rendered":"<p style=\"text-align: justify;\">El pasado 16 de julio, se celebr\u00f3 el <strong>22@Update Breakfast<\/strong>, una iniciativa de la Asociaci\u00f3n <strong>22@Network<\/strong>\u00a0<strong>BCN<\/strong> que mes a mes se constituye como un punto de encuentro clave para conocer las \u00faltimas tendencias tecnol\u00f3gicas y\u00a0empresariales.<\/p>\n<div style=\"width: 593px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" title=\"22@Network\" src=\"http:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg\" alt=\"\" width=\"583\" height=\"240\" \/><p class=\"wp-caption-text\">A la izquierda: Jos\u00e9 Antonio Ufano, Director General PUE con Ramon Salabert, Presidente de la Asociaci\u00f3n 22@Network bcn y Alfonso Luengo, Director Gerente de la Fundaci\u00f3n Tripartita<\/p><\/div>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">En su edici\u00f3n n\u00ba 102, el encuentro trat\u00f3 sobre el nuevo escenario que propone el RD Ley 4\/2015 para la reforma urgente del Sistema de Formaci\u00f3n Profesional para el Empleo. <strong>En la secci\u00f3n Up Date, Alfonso Luengo, Direct<\/strong><strong>or Gerente de la Fundaci\u00f3n Tripartita<\/strong>, habl\u00f3 en su ponencia \u201cUn nuevo horizonte para las empresas IT en el modelo de la formaci\u00f3n profesional para el empleo\u201d sobre los detalles del cambio de orientaci\u00f3n que propone la Reforma: <strong>un modelo de formaci\u00f3n basado en la anticipaci\u00f3n y en la detecci\u00f3n de las necesidades formativas de las organizaciones<\/strong>. Siendo este \u00faltimo, un aspecto de especial inter\u00e9s para las empresas del \u00e1mbito tecnol\u00f3gico donde la formaci\u00f3n continuada y la actualizaci\u00f3n de conocimientos son un requisito del todo ineludible.<\/p>\n<p><img decoding=\"async\" class=\" alignleft\" src=\"http:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-2.jpg\" alt=\"\" \/><\/p>\n<p style=\"text-align: justify;\">En su intervenci\u00f3n, Alfonso Luengo hizo referencia a los <strong>85.000 puestos de trabajo que en el a\u00f1o 2014 se quedaron sin cubrir debido a la falta de profesionales cualificados<\/strong>. En ese sentido, insisti\u00f3 en <strong>\u201cla importancia de alinear el sistema de formaci\u00f3n al sistema productivo\u201d<\/strong>.<br \/>\nEl nuevo escenario que propone la Reforma incorpora cambios significativos: un nuevo concepto y gesti\u00f3n de las entidades organizadoras; una ampliaci\u00f3n de las herramientas de gesti\u00f3n y ejecuci\u00f3n de la formaci\u00f3n, adem\u00e1s de <strong>una apertura hacia v\u00edas de formaci\u00f3n que buscan la eficiencia y la contribuci\u00f3n a la ocupaci\u00f3n<\/strong>, explic\u00f3 Luengo, donde se enmarca la formaci\u00f3n certificada y las certificaciones IT de fabricante.<\/p>\n<p style=\"text-align: justify;\"><strong>La secci\u00f3n El Innovador del Mes, estuvo representada por Jos\u00e9 Antonio Ufano, Director General de PUE<\/strong> quien, en su ponencia \u201cLa acreditaci\u00f3n de conocimientos: valor estrat\u00e9gico en el entorno empresarial IT\u201d, habl\u00f3 sobre el acceso de las empresas al conocimiento IT cualificado. Entre otros aspectos, destac\u00f3 el <strong>soporte que los organismos p\u00fablicos han dado a la formaci\u00f3n y certificaci\u00f3n oficial IT<\/strong>, reconociendo su valor y aportaci\u00f3n a la empleabilidad. Un apoyo, explic\u00f3, que se demuestra en las m\u00e1s de 30 acciones formativas que el Servicio P\u00fablico de Empleo Estatal (SEPE) ha ofertado y que incluyen curr\u00edculums y certificaciones dise\u00f1adas por las l\u00edderes tecnol\u00f3gicos a nivel mundial como Oracle, Cisco, Microsoft y Linux, entre otros. Se trata de un nuevo cat\u00e1logo de formaci\u00f3n, aclar\u00f3, que tambi\u00e9n se incorpora en los servicios p\u00fablicos de empleo auton\u00f3micos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" aligncenter\" src=\"http:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-3.jpg\" alt=\"\" width=\"346\" height=\"218\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>J.A. Ufano cit\u00f3 dos casos de \u00e9xito como ejemplo de formaci\u00f3n eficiente<\/strong>: el Centro de Tecnolog\u00edas Avanzadas de Arag\u00f3n y el Centro de Nuevas Tecnolog\u00edas de Galicia, donde, impartiendo formaci\u00f3n y certificaci\u00f3n oficial en distintas tecnolog\u00edas, se est\u00e1 <strong>consiguiendo un ratio de inserci\u00f3n laboral de m\u00e1s del 80%<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>El Presidente de la Asociaci\u00f3n 22@Network bcn, Ramon Salabert<\/strong>, clausur\u00f3 la jornada poniendo \u00e9nfasis en\u00a0<strong>\u201cla importancia de la formaci\u00f3n profesional como puente entre los trabajadores en situaci\u00f3n de desempleo y los nuevos puestos de trabajo que est\u00e1n surgiendo fruto de las nuevas tecnolog\u00edas\u201d<\/strong>.<\/p>\n<p style=\"text-align: justify;\">El 22@Update Breakfast n\u00ba102 remarc\u00f3, en l\u00edneas generales, la falta de profesionales cualificados, especialmente en el sector IT, as\u00ed como el <strong>necesario acercamiento entre la formaci\u00f3n y el \u00e1mbito laboral para fomentar la competitividad, la ocupaci\u00f3n y el desarrollo econ\u00f3mico<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Desde PUE nuestro m\u00e1s sincero agradecimiento a la Asociaci\u00f3n 22@network bcn por confiar en nosotros, a la Fundaci\u00f3n Tripartita por liderar y acompa\u00f1arnos en este encuentro y al Espai Pujades 350 del Col\u00b7legi Oficial d\u2019Infermeres i Infermers de Barcelona, un magn\u00edfico espacio donde tuvo lugar la jornada.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre los temas que se trataron:<br \/>\n<strong><span style=\"text-decoration: underline;\"><a style=\"color: #00bfff; text-decoration: underline;\" href=\"mailto:training@pue.es\" target=\"_blank\" rel=\"noopener noreferrer\">training@pue.es<\/a><\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de la Asociaci\u00f3n 22@Network\u00a0BCN que mes a mes se constituye como un punto de encuentro clave para conocer las \u00faltimas tendencias tecnol\u00f3gicas y\u00a0empresariales.<\/p>\n","protected":false},"author":1,"featured_media":106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[16,17,15],"class_list":{"0":"post-1716","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-corporate","8":"tag-22network-bcn","9":"tag-fundacion-tripartita","10":"tag-it"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn | PUE Blog<\/title>\n<meta name=\"description\" content=\"El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de 22@Network\u00a0BCN que constituye un punto de encuentro clave.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network BCN | PUE Blog\" \/>\n<meta property=\"og:description\" content=\"El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de 22@Network\u00a0BCN que constituye un punto de encuentro clave.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/\" \/>\n<meta property=\"og:site_name\" content=\"PUE Blog\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-21T06:05:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T20:14:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"583\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-blogpue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network BCN | PUE Blog\" \/>\n<meta name=\"twitter:description\" content=\"El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de 22@Network\u00a0BCN que constituye un punto de encuentro clave.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-blogpue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/\"},\"author\":{\"name\":\"admin-blogpue\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"headline\":\"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn\",\"datePublished\":\"2015-07-21T06:05:55+00:00\",\"dateModified\":\"2024-02-28T20:14:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/\"},\"wordCount\":709,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg\",\"keywords\":[\"22@Network Bcn\",\"Fundaci\u00f3n Tripartita\",\"IT\"],\"articleSection\":[\"Corporate\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/\",\"url\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/\",\"name\":\"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn | PUE Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg\",\"datePublished\":\"2015-07-21T06:05:55+00:00\",\"dateModified\":\"2024-02-28T20:14:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\"},\"description\":\"El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de 22@Network\u00a0BCN que constituye un punto de encuentro clave.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#primaryimage\",\"url\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg\",\"contentUrl\":\"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg\",\"width\":583,\"height\":240,\"caption\":\"pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.pue.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corporate\",\"item\":\"https:\/\/www.pue.es\/blog\/category\/corporate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pue.es\/blog\/#website\",\"url\":\"https:\/\/www.pue.es\/blog\/\",\"name\":\"PUE Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pue.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed\",\"name\":\"admin-blogpue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g\",\"caption\":\"admin-blogpue\"},\"sameAs\":[\"http:\/\/www.eu4.pue.es\/blog\"],\"url\":\"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn | PUE Blog","description":"El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de 22@Network\u00a0BCN que constituye un punto de encuentro clave.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/","og_locale":"es_ES","og_type":"article","og_title":"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network BCN | PUE Blog","og_description":"El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de 22@Network\u00a0BCN que constituye un punto de encuentro clave.","og_url":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/","og_site_name":"PUE Blog","article_published_time":"2015-07-21T06:05:55+00:00","article_modified_time":"2024-02-28T20:14:41+00:00","og_image":[{"width":583,"height":240,"url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg","type":"image\/jpeg"}],"author":"admin-blogpue","twitter_card":"summary_large_image","twitter_title":"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network BCN | PUE Blog","twitter_description":"El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de 22@Network\u00a0BCN que constituye un punto de encuentro clave.","twitter_image":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg","twitter_misc":{"Escrito por":"admin-blogpue","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#article","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/"},"author":{"name":"admin-blogpue","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"headline":"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn","datePublished":"2015-07-21T06:05:55+00:00","dateModified":"2024-02-28T20:14:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/"},"wordCount":709,"commentCount":0,"image":{"@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg","keywords":["22@Network Bcn","Fundaci\u00f3n Tripartita","IT"],"articleSection":["Corporate"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/","url":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/","name":"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn | PUE Blog","isPartOf":{"@id":"https:\/\/www.pue.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#primaryimage"},"image":{"@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg","datePublished":"2015-07-21T06:05:55+00:00","dateModified":"2024-02-28T20:14:41+00:00","author":{"@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed"},"description":"El pasado 16 de julio, se celebr\u00f3 el 22@Update Breakfast, una iniciativa de 22@Network\u00a0BCN que constituye un punto de encuentro clave.","breadcrumb":{"@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#primaryimage","url":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg","contentUrl":"https:\/\/www.pue.es\/blog\/wp-content\/uploads\/2023\/11\/breakfast22-1.jpg","width":583,"height":240,"caption":"pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pue.es\/blog\/pue-participa-con-la-fundacion-tripartita-en-el-breakfast-de-22network-bcn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.pue.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Corporate","item":"https:\/\/www.pue.es\/blog\/category\/corporate\/"},{"@type":"ListItem","position":3,"name":"PUE participa con la Fundaci\u00f3n Tripartita en el Breakfast de 22@Network Bcn"}]},{"@type":"WebSite","@id":"https:\/\/www.pue.es\/blog\/#website","url":"https:\/\/www.pue.es\/blog\/","name":"PUE Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pue.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pue.es\/blog\/#\/schema\/person\/c1100c902cc7a9230c60a397b03adaed","name":"admin-blogpue","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/10c64761a791b6c48b72d01ff9056b72d398a3caf12c9c7f96fae627d802ca23?s=96&d=mm&r=g","caption":"admin-blogpue"},"sameAs":["http:\/\/www.eu4.pue.es\/blog"],"url":"https:\/\/www.pue.es\/blog\/author\/admin-blogpue\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/1716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/comments?post=1716"}],"version-history":[{"count":0,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/posts\/1716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media\/106"}],"wp:attachment":[{"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/media?parent=1716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/categories?post=1716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pue.es\/blog\/wp-json\/wp\/v2\/tags?post=1716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}